{"id":11824,"date":"2025-12-08T14:15:19","date_gmt":"2025-12-08T11:15:19","guid":{"rendered":"https:\/\/grindeks.com\/?page_id=11824"},"modified":"2025-12-08T14:16:07","modified_gmt":"2025-12-08T11:16:07","slug":"analytical-services","status":"publish","type":"page","link":"https:\/\/grindeks.com\/en\/cdmo\/analytical-services\/","title":{"rendered":"Analytical Services"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/grindeks.com\/wp-content\/uploads\/2025\/10\/6-1-1024x1024.png\" alt=\"\" class=\"wp-image-11727\" style=\"width:126px;height:auto\" title=\"\" srcset=\"https:\/\/grindeks.com\/wp-content\/uploads\/2025\/10\/6-1-1024x1024.png 1024w, https:\/\/grindeks.com\/wp-content\/uploads\/2025\/10\/6-1-300x300.png 300w, https:\/\/grindeks.com\/wp-content\/uploads\/2025\/10\/6-1-150x150.png 150w, https:\/\/grindeks.com\/wp-content\/uploads\/2025\/10\/6-1-768x768.png 768w, https:\/\/grindeks.com\/wp-content\/uploads\/2025\/10\/6-1-480x480.png 480w, https:\/\/grindeks.com\/wp-content\/uploads\/2025\/10\/6-1-640x640.png 640w, https:\/\/grindeks.com\/wp-content\/uploads\/2025\/10\/6-1-720x720.png 720w, https:\/\/grindeks.com\/wp-content\/uploads\/2025\/10\/6-1-960x960.png 960w, https:\/\/grindeks.com\/wp-content\/uploads\/2025\/10\/6-1.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pale-cyan-blue-color\">Analytical Services<\/mark><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Analytical method development<\/li>\n\n\n\n<li>Analytical method validation, verification and transfer<\/li>\n\n\n\n<li>Nitrosamine and genotoxic impurity control testing and consulting<\/li>\n\n\n\n<li>Photostability and forced degradation studies<\/li>\n\n\n\n<li>Drug\u2013excipient compatibility studies<\/li>\n\n\n\n<li>Impurity identification studies<\/li>\n\n\n\n<li>Custom impurity reference standard standardization<\/li>\n\n\n\n<li>Intrinsic solubility studies<\/li>\n\n\n\n<li>Equilibrium solubility studies for BCS-based biowaivers<\/li>\n\n\n\n<li>IVRT method development and analysis<\/li>\n\n\n\n<li>Rheological behaviour<\/li>\n\n\n\n<li>Specific surface area determination<\/li>\n\n\n\n<li>Oxygen determination in the free volume of vials<\/li>\n\n\n\n<li>Osmolality analysis<\/li>\n\n\n\n<li>Particulate contamination testing (visible and sub-visible particles)<\/li>\n\n\n\n<li>Thermal cycle studies (freeze\u2013thaw and cool\u2013thaw cycles)<\/li>\n\n\n\n<li>Stability studies (accelerated, intermediate, long-term, in-use)<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pale-cyan-blue-color\">Available Equipment<\/mark><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Spectrometers (FTIR, UV)<\/li>\n\n\n\n<li>Refractometer<\/li>\n\n\n\n<li>Polarimeter<\/li>\n\n\n\n<li>Melting point apparatus<\/li>\n\n\n\n<li>Differential scanning calorimetry (DSC)<\/li>\n\n\n\n<li>Powder X-ray diffractometer (XRD)<\/li>\n\n\n\n<li>Nuclear magnetic resonance (NMR)\u00b9 <\/li>\n\n\n\n<li>HPLC systems (UV, PDA, RI), UPLC systems (UV, PDA, MS\/MS)<\/li>\n\n\n\n<li>GC systems (FID, HS-FID, TCD, MS, HS-MS)<\/li>\n\n\n\n<li>Electrophoresis system<\/li>\n\n\n\n<li>Potentiometric titrator<\/li>\n\n\n\n<li>Karl Fischer titrator and coulometer<\/li>\n\n\n\n<li>Xenon lamp photostability chamber<\/li>\n\n\n\n<li>Laser diffraction particle size analyser (PSD)<\/li>\n\n\n\n<li>IVRT diffusion system<\/li>\n\n\n\n<li>Rheometer<\/li>\n\n\n\n<li>Dissolution systems (online\/offline)<\/li>\n\n\n\n<li>BET specific surface area analyser<\/li>\n\n\n\n<li>Filter integrity testers (Pall Flowstar, Sartorius)<\/li>\n\n\n\n<li>Osmometer<\/li>\n\n\n\n<li>Liquid particle counter<\/li>\n\n\n\n<li>Turbidimeter<\/li>\n\n\n\n<li>Optical oxygen meter<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Analytical Services Available Equipment<\/p>\n","protected":false},"author":2,"featured_media":6601,"parent":11661,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11824","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/grindeks.com\/en\/wp-json\/wp\/v2\/pages\/11824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grindeks.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/grindeks.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/grindeks.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/grindeks.com\/en\/wp-json\/wp\/v2\/comments?post=11824"}],"version-history":[{"count":2,"href":"https:\/\/grindeks.com\/en\/wp-json\/wp\/v2\/pages\/11824\/revisions"}],"predecessor-version":[{"id":11826,"href":"https:\/\/grindeks.com\/en\/wp-json\/wp\/v2\/pages\/11824\/revisions\/11826"}],"up":[{"embeddable":true,"href":"https:\/\/grindeks.com\/en\/wp-json\/wp\/v2\/pages\/11661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grindeks.com\/en\/wp-json\/wp\/v2\/media\/6601"}],"wp:attachment":[{"href":"https:\/\/grindeks.com\/en\/wp-json\/wp\/v2\/media?parent=11824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}